{"id":65056,"date":"2016-04-28T12:26:41","date_gmt":"2016-04-28T10:26:41","guid":{"rendered":"http:\/\/agenturherzensfreude.com\/?p=65056"},"modified":"2016-04-28T12:26:41","modified_gmt":"2016-04-28T10:26:41","slug":"experiment-effektivitaet","status":"publish","type":"post","link":"https:\/\/agenturherzensfreude.com\/gb\/2016\/04\/28\/experiment-effektivitaet\/","title":{"rendered":"Experiment Effektivit\u00e4t"},"content":{"rendered":"<div class=\"pntrst_main_before_after\"><div class=\"pntrst-button-wrap\">\n\t\t\t\t\t\t\t<a data-pin-do=\"buttonBookmark\" data-pin-custom=\"\" href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\"><img data-recalc-dims=\"1\" decoding=\"async\" data-pin-nopin=\"1\" class=\"pntrst-custom-pin\" src=\"https:\/\/i0.wp.com\/agenturherzensfreude.com\/wp-content\/plugins\/bws-pinterest\/images\/pin.png?w=60&#038;ssl=1\" ><\/a>\n\t\t\t\t\t\t<\/div><\/div><p>Es ist erstaunlich wieviel Zeit wir verwenden, um uns und unsere Umgebung zu optimieren. Dank dem Internet finden wir Tricks, Tipps und erfahren ruckzuck, was wir in welcher Situation tun k\u00f6nnen. Es gibt Blogger, die uns \u00fcber alles M\u00f6gliche informieren. Wie man vegan kocht, wie man seine Kinder m\u00f6glichst angenehm gro\u00dfzieht, wie man sein Haus in Schuss h\u00e4lt, Beziehungsratgeber, Scheidungsexperten, DIY- Renovierungsexperten. Ach f\u00fcr alles und jedes Ding gibt es einen selbsterkl\u00e4rten &#8220;Experten&#8221;, den man per Google finden kann und von dessem KnowHow profitieren kann.<\/p>\n<p>Ich freue mich, dass ich immerzu f\u00fcndig werde, weil Mama google f\u00fcr fast alles einen Rat weiss. Doch es gibt auch durchaus Menschen, die das Ganze zu Ernst nehmen. Die ihren gesunden Menschenverstand und ihre innere Stimme ausblenden und wahllos das als richtig anerkennen, was ein selbsternannter Experte f\u00fcr richtig erkl\u00e4rt.<\/p>\n<p>Meine Hebamme hatte mir einmal davon berichtet, dass es viele Mamis gibt, die abends wenn das Baby endlich schl\u00e4ft, im Internet herumsuchen, wie sie eine bessere Mama werden k\u00f6nnen und was das Wehwehchen von heute denn sein k\u00f6nnte. Sie hatte bei mir immer gerne Kaffee getrunken und eine sch\u00f6ne Zeit gehabt, wenn es um die Vorsorge oder die Nachsorge ging. Sie hatte mir erkl\u00e4rt, das google ja gut und sch\u00f6n sei, aber manche Mamas halt nicht einsch\u00e4tzen k\u00f6nnen, was jetzt gerade richtig und falsch f\u00fcr sie ist und das oftmals das Internet eher einige Menschen verwirrt, als aufkl\u00e4rt. Ich war immer froh, wenn ich duschen oder Sport treiben konnte, weil es doch wichtig ist die &#8220;MAMA-Zeit&#8221; auch f\u00fcr sich zu nutzen. Jetzt wild herumzugooglen finde ich reine Zeitverschwendung, denn oftmals sind die Kinder einfach nur quengelig, weil es Mama gerade selbst ist, es aber nicht zugeben mag. KINDER sind die Spiegel unserer Seelen.<\/p>\n<p>Manchmal ist es nicht so effektiv nach etwas im Netz zu suchen, weil man es eigentlich bei sich selbst suchen sollte, anstatt im worldwideweb. Denn tief im Herzen wissen die meisten Menschen schon was richtig bzw. falsch f\u00fcr sie ist. Es ist sicherlich hilfreich zu sehen das Mama X ihrem Sohn K\u00fcrbismus zubereitet und wie, wenn aber die Prinzessin K\u00fcrbis auf den Tod nicht leiden kann, bringt es auch nicht ihr dies zu verabreichen. Es sei denn man putzt gerne ausgespucktes, farbenfrohes Mus auf.\u00a0 Also, jeder sollte einfach mal auf sich und sein Umfeld achten&#8211;OHNE an sich selbst zu (ver)zweifeln.<\/p>\n<p>Ich pers\u00f6nlich lasse mich gerne im Internet inspirieren. L\u00f6sungen finde ich in der Regel jedoch selbst f\u00fcr meine Probleme. Als Beziehungsratgeber w\u00fcrde ich mich nicht gerade bezeichnen. Allerdings berichte ich gerne von den komplizierten\/komplexen Momenten zwischen Mann und Frau und wie man auch noch nach Jahren an sich und der Beziehung &#8220;arbeiten&#8221; kann ohne sich zu \u00fcbernehmen ;O)).<\/p>\n<p>D\u00fcrfen wir heute noch einfach wir selbst sein? M\u00fcssen wir die perfekten Businessfrauen\/Businessm\u00e4nner ohne Makel sein? Darf heute noch jemand mit einem Sch\u00f6nheitsfehler herumlaufen und faltig sein? Darf auch jemand joggen gehen, der keine Hightech-Ausr\u00fcstung besitzt und mit Iphone ausger\u00fcstet ist, das ihn dank coolen Sounds begleitet und effektiver macht?<\/p>\n<p>Ich finde es schade, dass wir alles bewerten und optimieren m\u00fcssen. Ich tue es ja selbst immer, st\u00f6hn. Warum kann ich nicht mein Gegen\u00fcber einfach lieben, so wie er\/sie ist, ohne dass er etwas besonderes tut oder effektiv ist? Einfach um seiner\/ihrer selbst Willen?<\/p>\n<p>Seien wir doch einmal ehrlich. Wenn bei einem BlindDate jemand zugeben w\u00fcrde, dass er am liebsten auf der Couch herumlungert und dabei nichtssagend in die Luft starren w\u00fcrde&#8211;f\u00e4nden wir das als Frau\/Mann attraktiv? Das Bild an sich ist lustig-aber ist es in unserem heutigen Zeitalter moralisch vertretbar?<\/p>\n<p>Mir wurde am Vormittag gesagt, ich k\u00f6nnte auch mal einen Tag nichts tun, dann w\u00fcrde, ich am n\u00e4chsten Tag energiegeladen sein und k\u00f6nnte effektiver handeln.Die These an f\u00fcr sich macht Sinn und gef\u00e4llt mir. In der Umsetzung stellt sich das Ganze etwas problematisch dar:<\/p>\n<p>Wenn ich meinen Couchmodus aktiviere, und einen Vier-j\u00e4hrigen und eine Krabbelnde einfach einmal ganz sie selbst sein lasse und auch sonst weder im Haushalt noch im Home-Office etwas anpacke&#8230;ob ich dann morgen noch aus dem Haus komme&#8230;oder ob um mich herum \u00fcberall Riesenhaufen von Zeug herumliegen, und ich ersteinmal ein Zirkeltraining absolvieren m\u00fcsste, um \u00fcberhaupt meine Position von der Couch zu verlassen?!<\/p>\n<p>Jeder interpretiert Effektivit\u00e4t anders. Ich pers\u00f6nlich bin im Moment froh, wenn ich einen Punkt auf meiner To do Liste abhaken kann. Kleinkinder nehmen einen doch schon sehr in Anspruch. Aber sie sind liebenswert und zuckers\u00fc\u00df. Deswegen bin ich derzeit nicht so effektiv. Ich hoffe, dass mein Herz meinem Verstand beweist, dass es effektiver ist Dinge zu erledigen wenn sie dran sind und es gerade fluppt, als sich starr an der to do Liste festzukrallen, in der Hoffnung effektiv und optimal zu sein.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"pntrst_main_before_after\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Es ist erstaunlich wieviel Zeit wir verwenden, um uns und unsere Umgebung zu optimieren. Dank dem Internet finden wir Tricks, Tipps und erfahren ruckzuck, was wir in welcher Situation tun k\u00f6nnen. Es gibt Blogger, die uns \u00fcber alles M\u00f6gliche informieren&#8230;. <a class=\"more-link\" href=\"https:\/\/agenturherzensfreude.com\/gb\/2016\/04\/28\/experiment-effektivitaet\/#more-65056\">Continue Reading &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[2710],"tags":[],"class_list":["post-65056","post","type-post","status-publish","format-standard","hentry","category-allgemein","clear"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"gb","enabled_languages":["de","gb"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"gb":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Experiment Effektivit\u00e4t - Getting married in denmark<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Experiment Effektivit\u00e4t - Getting married in denmark\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/\" \/>\n<meta property=\"og:site_name\" content=\"Getting married in denmark\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-28T10:26:41+00:00\" \/>\n<meta name=\"author\" content=\"agenturherzensfreude\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"agenturherzensfreude\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/2016\\\/04\\\/28\\\/experiment-effektivitaet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/2016\\\/04\\\/28\\\/experiment-effektivitaet\\\/\"},\"author\":{\"name\":\"agenturherzensfreude\",\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/#\\\/schema\\\/person\\\/d915bfc87b51c94fcdf65c9dcad2ed58\"},\"headline\":\"Experiment Effektivit\u00e4t\",\"datePublished\":\"2016-04-28T10:26:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/2016\\\/04\\\/28\\\/experiment-effektivitaet\\\/\"},\"wordCount\":844,\"commentCount\":0,\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agenturherzensfreude.com\\\/2016\\\/04\\\/28\\\/experiment-effektivitaet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/2016\\\/04\\\/28\\\/experiment-effektivitaet\\\/\",\"url\":\"https:\\\/\\\/agenturherzensfreude.com\\\/2016\\\/04\\\/28\\\/experiment-effektivitaet\\\/\",\"name\":\"Experiment Effektivit\u00e4t - Getting married in denmark\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/#website\"},\"datePublished\":\"2016-04-28T10:26:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/#\\\/schema\\\/person\\\/d915bfc87b51c94fcdf65c9dcad2ed58\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/2016\\\/04\\\/28\\\/experiment-effektivitaet\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agenturherzensfreude.com\\\/2016\\\/04\\\/28\\\/experiment-effektivitaet\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/2016\\\/04\\\/28\\\/experiment-effektivitaet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agenturherzensfreude.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experiment Effektivit\u00e4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/#website\",\"url\":\"https:\\\/\\\/agenturherzensfreude.com\\\/\",\"name\":\"Getting married in denmark\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agenturherzensfreude.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agenturherzensfreude.com\\\/#\\\/schema\\\/person\\\/d915bfc87b51c94fcdf65c9dcad2ed58\",\"name\":\"agenturherzensfreude\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/324c2a9e1ed8995ab92ad81dd07a158acc8f72f72d4af7e53f6536e7d6e583f3?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/324c2a9e1ed8995ab92ad81dd07a158acc8f72f72d4af7e53f6536e7d6e583f3?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/324c2a9e1ed8995ab92ad81dd07a158acc8f72f72d4af7e53f6536e7d6e583f3?s=96&d=identicon&r=g\",\"caption\":\"agenturherzensfreude\"},\"description\":\"ich erm\u00f6gliche Paaren die standesamtliche Hochzeit in D\u00e4nemark, auch ohne Geburtsurkunde. Blitzhochzeiten sind m\u00f6glich. Die Trauung kann auf Englisch oder Deutsch stattfinden. Es ist m\u00f6glich ohne eigene Trauzeugen anzureisen. Die Traumhochzeit in D\u00e4nemark kann auch an besonderen Orten stattfinden: Beispielsweise Hochzeit im Hotel oder eine Strandhochzeit. Das Paar erh\u00e4lt nach der Trauung seine Heiratsurkunde, die f\u00fcnfsprachig und weltweit g\u00fcltig ist. Ich arbeite mit Fotografen, Visagisten und Hoteliers zusammen. Mein Blog gilt ausserdem zur Inspiration und Motivation in allen Lebenslagen (Selbstmotivation, Beziehungstipps, Hochzeitsideen, Alltagtipps)\",\"url\":\"https:\\\/\\\/agenturherzensfreude.com\\\/gb\\\/author\\\/agenturherzensfreude\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Experiment Effektivit\u00e4t - Getting married in denmark","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/","og_locale":"en_GB","og_type":"article","og_title":"Experiment Effektivit\u00e4t - Getting married in denmark","og_url":"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/","og_site_name":"Getting married in denmark","article_published_time":"2016-04-28T10:26:41+00:00","author":"agenturherzensfreude","twitter_card":"summary_large_image","twitter_misc":{"Written by":"agenturherzensfreude","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/#article","isPartOf":{"@id":"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/"},"author":{"name":"agenturherzensfreude","@id":"https:\/\/agenturherzensfreude.com\/#\/schema\/person\/d915bfc87b51c94fcdf65c9dcad2ed58"},"headline":"Experiment Effektivit\u00e4t","datePublished":"2016-04-28T10:26:41+00:00","mainEntityOfPage":{"@id":"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/"},"wordCount":844,"commentCount":0,"articleSection":["Allgemein"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/","url":"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/","name":"Experiment Effektivit\u00e4t - Getting married in denmark","isPartOf":{"@id":"https:\/\/agenturherzensfreude.com\/#website"},"datePublished":"2016-04-28T10:26:41+00:00","author":{"@id":"https:\/\/agenturherzensfreude.com\/#\/schema\/person\/d915bfc87b51c94fcdf65c9dcad2ed58"},"breadcrumb":{"@id":"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/agenturherzensfreude.com\/2016\/04\/28\/experiment-effektivitaet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/agenturherzensfreude.com\/"},{"@type":"ListItem","position":2,"name":"Experiment Effektivit\u00e4t"}]},{"@type":"WebSite","@id":"https:\/\/agenturherzensfreude.com\/#website","url":"https:\/\/agenturherzensfreude.com\/","name":"Getting married in denmark","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agenturherzensfreude.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/agenturherzensfreude.com\/#\/schema\/person\/d915bfc87b51c94fcdf65c9dcad2ed58","name":"agenturherzensfreude","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/324c2a9e1ed8995ab92ad81dd07a158acc8f72f72d4af7e53f6536e7d6e583f3?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/324c2a9e1ed8995ab92ad81dd07a158acc8f72f72d4af7e53f6536e7d6e583f3?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/324c2a9e1ed8995ab92ad81dd07a158acc8f72f72d4af7e53f6536e7d6e583f3?s=96&d=identicon&r=g","caption":"agenturherzensfreude"},"description":"ich erm\u00f6gliche Paaren die standesamtliche Hochzeit in D\u00e4nemark, auch ohne Geburtsurkunde. Blitzhochzeiten sind m\u00f6glich. Die Trauung kann auf Englisch oder Deutsch stattfinden. Es ist m\u00f6glich ohne eigene Trauzeugen anzureisen. Die Traumhochzeit in D\u00e4nemark kann auch an besonderen Orten stattfinden: Beispielsweise Hochzeit im Hotel oder eine Strandhochzeit. Das Paar erh\u00e4lt nach der Trauung seine Heiratsurkunde, die f\u00fcnfsprachig und weltweit g\u00fcltig ist. Ich arbeite mit Fotografen, Visagisten und Hoteliers zusammen. Mein Blog gilt ausserdem zur Inspiration und Motivation in allen Lebenslagen (Selbstmotivation, Beziehungstipps, Hochzeitsideen, Alltagtipps)","url":"https:\/\/agenturherzensfreude.com\/gb\/author\/agenturherzensfreude\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4YXCW-gVi","jetpack_likes_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/agenturherzensfreude.com\/gb\/wp-json\/wp\/v2\/posts\/65056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenturherzensfreude.com\/gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agenturherzensfreude.com\/gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agenturherzensfreude.com\/gb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agenturherzensfreude.com\/gb\/wp-json\/wp\/v2\/comments?post=65056"}],"version-history":[{"count":25,"href":"https:\/\/agenturherzensfreude.com\/gb\/wp-json\/wp\/v2\/posts\/65056\/revisions"}],"predecessor-version":[{"id":65125,"href":"https:\/\/agenturherzensfreude.com\/gb\/wp-json\/wp\/v2\/posts\/65056\/revisions\/65125"}],"wp:attachment":[{"href":"https:\/\/agenturherzensfreude.com\/gb\/wp-json\/wp\/v2\/media?parent=65056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agenturherzensfreude.com\/gb\/wp-json\/wp\/v2\/categories?post=65056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agenturherzensfreude.com\/gb\/wp-json\/wp\/v2\/tags?post=65056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}